{"id":474,"date":"2020-06-03T21:45:40","date_gmt":"2020-06-04T00:45:40","guid":{"rendered":"https:\/\/www.granlogiaregularargentina.org\/glra\/?p=474"},"modified":"2020-06-03T21:45:40","modified_gmt":"2020-06-04T00:45:40","slug":"niunamenos","status":"publish","type":"post","link":"https:\/\/www.granlogiaregularargentina.org\/glra\/blog\/2020\/06\/03\/niunamenos\/","title":{"rendered":"#NiUnaMenos"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"933\" height=\"445\" src=\"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-content\/uploads\/2020\/06\/Ni-una-menos.jpg\" alt=\"\" class=\"wp-image-475\" srcset=\"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-content\/uploads\/2020\/06\/Ni-una-menos.jpg 933w, https:\/\/www.granlogiaregularargentina.org\/glra\/wp-content\/uploads\/2020\/06\/Ni-una-menos-300x143.jpg 300w, https:\/\/www.granlogiaregularargentina.org\/glra\/wp-content\/uploads\/2020\/06\/Ni-una-menos-768x366.jpg 768w\" sizes=\"auto, (max-width: 933px) 100vw, 933px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Valle de Buenos Aires, Mi\u00e9rcoles 3 de\nJunio de 2020<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">QQHHMM y QQHH Todxs de GLRA:.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tri\u00e1ngulo Eva Duarte<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ni Una Menos! <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro del Gran Movimientx Feminista\nArgentinx, hoy conmemoramos la Marcha, el encuentro o la convocatoria, como se\nla reconoce de Ni Una Menos, que se produjo el 3 de Juino de 2015, a ra\u00edz del\naumento de femicidios en el pa\u00eds y en el mundo que d\u00eda a d\u00eda crec\u00edan\nestad\u00edsticamente y que mujeres periodistas y representantes de la cultura\nautoconvocaron por los medios de comunicaci\u00f3n y las redes sociales y que ha\nfortalecido y ampliado las fronteras de la acci\u00f3n colectiva en el campo de las marchas,\nbatallas y luchas por la reivindicaciones y los derechos de g\u00e9nero. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recordando siempre que, un 1ro de Mayo de\n1890, Virginia Bolten, encabez\u00f3 la primera manifestaci\u00f3n en conmemoraci\u00f3n de\nlos M\u00e1rtires de Chicago, y como insignia, se present\u00f3 levantando una bandera\nnegra y letras rojas que proclamaba la consigna: \u201c1 de Mayo, Fraternidad\nUniversal\u201d ha sido la primera mujer oradora en una concentraci\u00f3n obrera\npronunciando un discurso revolucionario frente a los trabajadores de la\nRefinar\u00eda Argentina.&nbsp;&nbsp; Las Trabajadoras\nhan salido en sus primeras luchas por reclamos justos de los derechos laborales\ny han sido pioneras en las batallas x la emancipaci\u00f3n de la clase trabajadora,\nen ese devenir, las marcas de la violencia, las violencias en los diferentes\n\u00e1mbitos que han padecido las mujeres: en el dom\u00e9stico, en el institucional, en\nel mundo laboral, desde los distintos dispositivos discursivos, educativos, los\nmandatos familiares, etc. Con la profundizaci\u00f3n de la desertizaci\u00f3n\n(degradaci\u00f3n) &nbsp;de los Derecho Humanos que\nnos ha dejado el neoliberalismo en nuestras sociedades y mientras no se\nimplementen f\u00f3rmulas antipatriarcales adecuadas. Hoy\nvolvemos a autoconvocarnos con diferentes actividades virtuales debido a la\nPandemia producida por el COVID19 que, encima del terrible momento que estamos\ntransitando a nivel global, crecen m\u00e1s a\u00fan las violencias de g\u00e9nero en el\n\u00e1mbito dom\u00e9stico dejando m\u00e1s v\u00edctimas de femicidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, reconocemos que en el devenir de los movimientos y procesos\nsociales,&nbsp; con la ampliaci\u00f3n y\nrestituci\u00f3n de derechos desde la implementaci\u00f3n la pol\u00edticas p\u00fablicas en el\n\u00e1rea de los derechos de g\u00e9nero y en acci\u00f3n conjunta con la coordinaci\u00f3n y la\nincorporaci\u00f3n de las perspectivas de g\u00e9nero en los distintos \u00e1mbitos\ninstitucionales. La ESI como sello en la Educaci\u00f3n Nacional, la mayor\u00eda de\nellas encaradas siempre por gobiernos que consideraron la inclusi\u00f3n y justicia\nsocial como premisa principal en el rol del Estado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed exponemos los datos actualizados al\nd\u00eda de fecha publicados por el Observatorio de las Violencias de G\u00e9nero \u201cAhora\nQue S\u00ed Nos Ven\u201d, justamente hoy 3 de Junio que se cumplen cinco a\u00f1os del primer\nNi Una Menos, dando a conoce las cifras de\nfemicidios en Argentina entre el 3 de junio de 2015 y el 25 de mayo de 2020,\nelaboradas a partir del an\u00e1lisis de medios gr\u00e1ficos y digitales de todo el pa\u00eds:\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA 5 a\u00f1os del grito feminista de\n#NiUnaMenos, los datos relevados de medios gr\u00e1ficos y digitales de todo el pa\u00eds\nnos muestran que la violencia machista no ha dejado de existir. Del 3 de junio\nde 2015 al 25 de mayo de este a\u00f1o, se registraron 1450 femicidios, uno cada 30\nhoras.<br>\nLas cifras nos dicen que el lugar donde m\u00e1s\nexpuestas estamos las mujeres es nuestro hogar desterr\u00e1ndose el mito del\ncallej\u00f3n oscuro y el desconocido que nos asesinaba. En estos 5 a\u00f1os el 64,6% de\nlos femicidios ocurri\u00f3 dentro de la vivienda de la v\u00edctima.<br>\nAl mismo tiempo, hemos relevado que el 83% de\nlos femicidas formaban parte del c\u00edrculo \u00edntimo o conocido de las v\u00edctimas, el\n66% de los femicidios fueron cometidos por la pareja o ex pareja de la v\u00edctima.\nAquellos que dicen amarnos, nos matan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debemos recordar que detr\u00e1s de cada femicidio\nhay una familia, hay madres, padres, hermanes e hijes. En estos cinco a\u00f1os,\n1527 ni\u00f1es perdieron a sus madres a causa de la violencia machista. Elles\ntambi\u00e9n son v\u00edctimas de las violencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo de estos a\u00f1os, desde el\nObservatorio Ahora que s\u00ed nos ven hemos exigido la implementaci\u00f3n de\nlegislaciones imprescindibles para romper con las desigualdades y estereotipos\nque sostienen estas violencias, como la Ley de Educaci\u00f3n Sexual Integral y la\nLey Micaela.<br>\nDel 3 de junio de 2015 al 25 de mayo de 2020 el\n18,3% de las v\u00edctimas de femicidio hab\u00eda realizado una denuncia previa y el\n8,4% ten\u00eda medidas de protecci\u00f3n. En este sentido, continuamos expresando que\nes sumamente importante que la Justicia act\u00fae con celeridad, tome medidas de\nprotecci\u00f3n con perspectiva de g\u00e9nero y controle el efectivo cumplimiento de las\nmismas, siendo para ello central el rol<a href=\"#_edn1\">[i]<\/a>\nde las fuerzas de seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, continuamos luchando por una\nsociedad m\u00e1s justa e igualitaria. La marea feminista que invadi\u00f3 las calles de todo\nel pa\u00eds y que puso en la agenda medi\u00e1tica y pol\u00edtica a las violencias de g\u00e9nero\nhace cinco a\u00f1os, logr\u00f3 abrir el camino a un proceso de transformaci\u00f3n social.\nUn camino en el que no estamos solas, porque fuimos construyendo y consolidando\nredes solidarias y feministas, que nos sostienen y en las que luchamos d\u00eda a\nd\u00eda por nuestro derecho a vivir una vida libre de violencias.\u201d<a href=\"#_edn2\">[ii]<\/a><br>\nLevantamos como premisas clave para trabajar en\nla acci\u00f3n colectiva de los Derechos de G\u00e9nero las siguientes pautas:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Conciencia y Praxis Activa para lograr tender lazos\nde Solidaridad entre Nosotrxs !!! Es decir, a partir de la Sororidad: la\nsolidaridad entre las mujeres, y <\/li><li>Es important\u00edsimo tener conciencia activa\ndiariamente: <\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Seguir\ntrabajando en programas y acci\u00f3n en cuanto a la asistencia a v\u00edctimas de la violencia de g\u00e9nero a partir de\nla incorporaci\u00f3n y profundizaci\u00f3n en todas las \u00e1reas de las pol\u00edticas p\u00fablicas\ny de las pr\u00e1cticas privadas, la perspectiva de g\u00e9nero y la agenda de temas\nfeministas que ha tejido el encuentro de mujeres en m\u00faltiples manifestaciones e\ninstituciones y reivindicamos la herramienta del paro de mujeres como sello del\nmovimientx feminista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queremos\ncerrar esta nota a partir de la enunciaci\u00f3n de los RECLAMOS y REIVINDICACIONES\nfrente al MALTRATO que vienen enarbol\u00e1ndose en las marchas de NI UNA MENOS y\ncuyos slogans son m\u00e1s que significativos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cTrabajadoras somos todas\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;\u201cConciencia\ny Praxis activa\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cVer las otras violencias\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cVisibilizar para cortar el c\u00edrculo de la\nviolencia\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cNi una Menos, vivas, libres y desendeudades\nnos queremos\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cSomos la nieta de la bruja que no pudieron\nquemar\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cNos est\u00e1n matando\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cNo nos maten m\u00e1s\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cPELEAMOS CON EL CORAZON EN LA MANO Y NO\nNOS VAMOS A AGACHAR NUNCA\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cM\u00e1s Femicidios que d\u00edas\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cAhora que s\u00ed nos ven\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuvimos\nel honor de manifestarnos y de estar presentes en cuerpo y alma en en esas\nMarchas con nuestras compa\u00f1erxs y tambi\u00e9n nuestrxs hijxs y damos fe que en las\nmismas se respira LIBERTAD, IGUALDAD, FRATERNIDAD Y SORIDAD!!!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Firma:\n<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Mar\u00eda\nRemedios del Valle <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Presidenta\ndel Tri\u00e1ngulo Eva Duarte de GLRA:.<br><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ednref1\">[i]<\/a> FUENTE DE INFORMACION: Observatorio de las Violencias de G\u00e9nero\n\u201cAhora Que S\u00ed Nos Ven\u201d por Facebook.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/niunamenos?__eep__=6&amp;source=feed_text&amp;epa=HASHTAG&amp;__xts__%5B0%5D=68.ARCH_xX5gwPCfxPgtHrse6rE4bpOpTGh4vOeTSYl4Y44OV_hQr__YTU4JyAcOvUQHZMb7BD3JQraXHxIj7g02eQsBiTrYpXhkRNkGtfch3FDiM4Br-b2uH4dVdC_HUCtGh17jST1e5ERaB3cW5gPaEgHfLE_RDZbLHLDeHq9t4xcVoKVnS6aHkq3IwjvjAXoa0UJ8w10cG9kEaNVESZXNgFaCaZmnXVKsw3tDvR6Kpk6EhwgUFClA-drDNkkPFYLQpYqVNXHDBa-QMaXY4vz_ko1h-w7IddLI6dERGOuHsWl0H65kZxFeg811iy9YDhFZGGUR5ZENdL919lNhUld&amp;__tn__=%2ANKH-R\">#NiUnaMenos<\/a><br>\n<a href=\"https:\/\/www.facebook.com\/hashtag\/vivasnosqueremos?__eep__=6&amp;source=feed_text&amp;epa=HASHTAG&amp;__xts__%5B0%5D=68.ARCH_xX5gwPCfxPgtHrse6rE4bpOpTGh4vOeTSYl4Y44OV_hQr__YTU4JyAcOvUQHZMb7BD3JQraXHxIj7g02eQsBiTrYpXhkRNkGtfch3FDiM4Br-b2uH4dVdC_HUCtGh17jST1e5ERaB3cW5gPaEgHfLE_RDZbLHLDeHq9t4xcVoKVnS6aHkq3IwjvjAXoa0UJ8w10cG9kEaNVESZXNgFaCaZmnXVKsw3tDvR6Kpk6EhwgUFClA-drDNkkPFYLQpYqVNXHDBa-QMaXY4vz_ko1h-w7IddLI6dERGOuHsWl0H65kZxFeg811iy9YDhFZGGUR5ZENdL919lNhUld&amp;__tn__=%2ANKH-R\">#VivasNosQueremos<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valle de Buenos Aires, Mi\u00e9rcoles 3 de Junio de 2020 QQHHMM y QQHH Todxs de GLRA:. Tri\u00e1ngulo Eva Duarte Ni Una Menos! Dentro del Gran Movimientx Feminista Argentinx, hoy conmemoramos la Marcha, el encuentro o la convocatoria, como se la reconoce de Ni Una Menos, que se produjo el 3 de Juino de 2015, a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-474","post","type-post","status-publish","format-standard","hentry","category-comunicados-glra"],"_links":{"self":[{"href":"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-json\/wp\/v2\/posts\/474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-json\/wp\/v2\/comments?post=474"}],"version-history":[{"count":1,"href":"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-json\/wp\/v2\/posts\/474\/revisions"}],"predecessor-version":[{"id":476,"href":"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-json\/wp\/v2\/posts\/474\/revisions\/476"}],"wp:attachment":[{"href":"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-json\/wp\/v2\/media?parent=474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-json\/wp\/v2\/categories?post=474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granlogiaregularargentina.org\/glra\/wp-json\/wp\/v2\/tags?post=474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}